{"id":20287,"date":"2020-07-10T16:13:13","date_gmt":"2020-07-10T14:13:13","guid":{"rendered":"https:\/\/cosyowl.com\/fr\/guides\/guide-debutant-pour-fabriquer-une-bougie-2"},"modified":"2025-10-10T15:40:05","modified_gmt":"2025-10-10T13:40:05","slug":"guide-debutant-pour-fabriquer-une-bougie","status":"publish","type":"post","link":"https:\/\/cosyowl.com\/fr\/guides\/guide-debutant-pour-fabriquer-une-bougie","title":{"rendered":"Guide D\u00e9butant Pour Fabriquer Une Bougie"},"content":{"rendered":" \r\n<p>Nous sommes heureux de vous faire d\u00e9couvrir notre premier guide support pour ceux qui d\u00e9butent dans la fabrication de bougies maison. Faire sa premi\u00e8re bougie est une entreprise amusante et agr\u00e9able, \u00e0 laquelle beaucoup prennent go\u00fbt, gr\u00e2ce \u00e0 l\u2019abondance de fabuleuses huiles parfum\u00e9s naturelles et de colorants disponibles sur notre site.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Pr\u00e9paration<\/h2>\r\n\r\n\r\n\r\n<p>Tout d\u2019abord, vous devez d\u00e9cider du type de cire, du colorant et de l\u2019huile que vous souhaitez utiliser pour faire votre bougie. Rappelez vous qu\u2019exp\u00e9rimenter avec des combinations fait partie du plaisir. N\u2019ayez pas peur si vous vous trompez, vous allez apprendre d\u00e8s que commencerez, et notre nouvelle vid\u00e9o en partenariat avec Cosy &amp; Country vous sera tr\u00e8s utile \u00e0 l\u2019avenir. Peut \u00eatre choisirez-vous de commencer avec des petits moules ou contenants lors de votre premi\u00e8re exp\u00e9rience. Vous verrez sur notre liste de cires \u00e0 bougie que vous pouvez choisir parmi diff\u00e9rents types de cires.<\/p>\r\n\r\n\r\n\r\n<p>Afin de mesurer la quantit\u00e9 de cire n\u00e9cessaire, remplissez votre moule ou contenant avec de l\u2019eau, mesurez la quantit\u00e9 d\u2019eau et arrondissez au dixi\u00e8me de ml sup\u00e9rieur. D\u00e9duisez ensuite 20% du chiffre obtenu, ceci vous donnera le chiffre en gramme dont vous avez besoin. 1ml d\u2019eau est \u00e9gal \u00e0 un gramme d\u2019eau, ils sont donc \u00e9gaux, mais la cire a une densit\u00e9 l\u00e9g\u00e8rement moindre par rapport \u00e0 l\u2019eau, nous d\u00e9duisons donc 20% pour obtenir la quantit\u00e9 de cire n\u00e9cessaire. Par exemple :&nbsp;&nbsp;<\/p>\r\n\r\n\r\n\r\n<p>495ml d\u2019eau dans un contenant\/moule \u2013 arrondissez \u00e0 500ml. D\u00e9duisez 20% du chiffre (100), ce qui vous donne 400 \u2013 vous avez donc besoin de 400g de cire.&nbsp;<\/p>\r\n\r\n\r\n\r\n<p>Pr\u00e9parez maintenant l\u2018espace que vous allez utiliser pour fabriquer vos bougies et assurez vous que tout d\u00e9bordement soit facile \u00e0 retirer. La cire peut \u00eatre p\u00e9nible \u00e0 retirer. Assurez-vous d\u2019avoir de l\u2019eau chaude et un chiffon or de l\u2018essuie-tout pour nettoyer tout d\u00e9bordement.<\/p>\r\n\r\n\r\n\r\n<p>Evitez tout contact avec la peau et surtout avec les yeux. Au cas ou vous auriez de la cire dans les yeux, ne cherchez pas \u00e0 la retirer vous-m\u00eame, faites appel \u00e0 un professionnel de sant\u00e9. M\u00eame si cela peut \u00eatre tr\u00e8s inconfortable et m\u00eame un peu douloureux de se mettre de la cire sur la peau, en g\u00e9n\u00e9ral celle-ci peut \u00eatre d\u00e9coll\u00e9e facilement ou rinc\u00e9e \u00e0 l\u2019eau chaude. Assurez-vous que la peau ne reste pas rouge ou d\u00e9color\u00e9e, ce qui pourrait indiquer une r\u00e9action allergique.&nbsp;<\/p>\r\n\r\n\r\n\r\n<p>Essayer d\u2019\u00e9viter de jeter la cire dans votre \u00e9vier car cela peut le bloquer. De fa\u00e7on similaire, ne lavez pas les contenants \u00e0 bougies ou les moules dans le lave-vaisselle.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">2\u00e8me Phase \u2013 Pr\u00e9parez et faire fondre la cire<\/h2>\r\n\r\n\r\n\r\n<p>Remplissez une grande casserole avec de l\u2019eau chaude jusqu\u2019\u00e0 \u00e0-peu-pr\u00e8s la moiti\u00e9 en vous assurant qu\u2019il reste assez de place pour mettre une casserole plus petite dedans pour faire fondre la cire. Placez la cire solide dans la petite casserole et d\u00e9posez la dans la grande. Assurez vous que l\u2019eau chaude ne puisse pas aller dans la petite casserole. Portez l\u2019eau \u00e0 \u00e9bullition. La cire commencera \u00e0 fondre. Vous pouvez touiller avec une spatule en bois (jetable) mais ceci n\u2019est pas n\u00e9cessaire. Cependant, avoir une spatule \u00e0 port\u00e9 de main vous sera utile lorsque vous ajouterez le colorant et le parfum.<\/p>\r\n\r\n\r\n\r\n<p>Utilisez un thermom\u00e8tre \u00e0 cire pour surveiller la temp\u00e9rature de la cire. Un thermom\u00e8tre standard de cuisine suffi, mais rappelez-vous qu\u2019il faudra le nettoyer efficacement avant de le r\u00e9utiliser en cuisine.<\/p>\r\n\r\n\r\n\r\n<p>Pour la paraffine, la temp\u00e9rature doit \u00eatre entre 50\u00b0c et 60\u00b0c.<\/p>\r\n\r\n\r\n\r\n<p>Pour la cire de soja, la temp\u00e9rature doit \u00eatre entre 76\u00b0c et 82\u00b0c.<\/p>\r\n\r\n\r\n\r\n<p>Pour les cires v\u00e9g\u00e9tales, la temp\u00e9rature doit \u00eatre entre 47\u00b0c et 49\u00b0c.<\/p>\r\n\r\n\r\n\r\n<p>Par le gel \u00e0 bougie, la temp\u00e9rature doit \u00eatre entre 94\u00b0c et 104\u00b0c.<\/p>\r\n\r\n\r\n\r\n<div class=\"wp-block-group\">\r\n<div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\r\n<figure class=\"wp-block-gallery columns-2 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\r\n<ul class=\"blocks-gallery-grid\">\r\n<li class=\"blocks-gallery-item\">\r\n<figure><img decoding=\"async\" class=\"wp-image-732\" src=\"https:\/\/cosyowl.com\/wp-content\/uploads\/2021\/08\/Screen-Shot-2020-07-09-at-11.04.51-3-1024x576.png\" alt=\"\" \/><\/figure>\r\n<\/li>\r\n<li class=\"blocks-gallery-item\">\r\n<figure><img decoding=\"async\" class=\"wp-image-734\" src=\"https:\/\/cosyowl.com\/wp-content\/uploads\/2021\/08\/Screen-Shot-2020-07-09-at-11.06.11-1-1024x576.png\" alt=\"\" data-id=\"734\" \/><\/figure>\r\n<\/li>\r\n<\/ul>\r\n<\/figure>\r\n<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">3<sup>\u00e8me<\/sup> Phase \u2013 Ajoutez la m\u00e8che<\/h2>\r\n\r\n\r\n\r\n<p>Si vous utilisez des <a href=\"https:\/\/www.cosyowl.com\/fournitures-de-bougies\/supplements-pour-la-fabrication-de-bougies\/points-de-colle\">points de colles<\/a> Cosy Owl, placez la m\u00e8che au centre de votre pot. Pour vous assurer que la m\u00e8che est bien centr\u00e9e, munissez vous de votre <a href=\"https:\/\/www.cosyowl.com\/fr\/wick-outil-centrage\">outil de centrage de m\u00e8che<\/a>, et placez votre m\u00e8che dans le trou pr\u00e9vu \u00e0 cet effet. Si vous ne souhaitez pas utiliser des points de colles, fixez la m\u00e8che \u00e0 un support de m\u00e8che m\u00e9tallique, que vous pouvez ensuite placer dans le pot\/moule et maintenez-le avec une spatule lorsque vous versez la cire fondue. Vous pouvez \u00e9galement ins\u00e9rer la m\u00e8che dans le fond du pot\/moule avec la spatule une fois la cire chaude vers\u00e9e.<\/p>\r\n\r\n\r\n\r\n<p>Sinon, vous pouvez \u00e9galement coller de la p\u00e2te adh\u00e9sive type Blu-Tack sur le dessous du support de m\u00e8che en m\u00e9tal.<\/p>\r\n\r\n\r\n\r\n<div class=\"wp-block-image\">\r\n<figure class=\"size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-733\" src=\"https:\/\/cosyowl.com\/wp-content\/uploads\/2021\/08\/Screen-Shot-2020-07-09-at-11.06.35-1-1024x574.png\" alt=\"\" width=\"384\" height=\"216\" \/><\/figure>\r\n<\/div>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">4<sup>\u00e8me<\/sup> Phase \u2013 Ajoutez colorant et parfum<\/h2>\r\n\r\n\r\n\r\n<p>Vous allez d\u00e9sormais ajouter votre colorant \u00e0 la cire fondue. Plus vous ajoutez de colorant plus la couleur de la bougie sera forte une fois termin\u00e9e. Vous allez tout de suite avoir une id\u00e9e sur la couleur lorsque vous versez le colorant dans la casserole. Ajoutez-en petit \u00e0 petit jusqu\u2019\u00e0 ce que vous obteniez la couleur souhait\u00e9e. Assurez vous que tous les copeaux soient fondus avant d\u2019ajouter l\u2019huile parfum\u00e9e.<\/p>\r\n\r\n\r\n\r\n<p>Maintenant, ajoutez votre huile parfum\u00e9e et m\u00e9langez doucement pour \u00e9viter les bulles d\u2019air. Faites comme si vous faisiez un g\u00e2teau. Assurez-vous de toujours m\u00e9langer pour que le parfum se diffuse dans toute la cire. Attention \u00e0 ne pas trop aromatiser votre bougie car d\u2019odeur peut \u00eatre tr\u00e8s forte ou trop s\u2019impr\u00e9gner dans la pi\u00e8ce.<\/p>\r\n\r\n\r\n\r\n<p>N\u2019oubliez pas que vous pouvez m\u00e9langer diff\u00e9rents colorants et parfum avec la cire de bougie si vous vous en sentez le courage. Ne vous inqui\u00e9tez pas si les m\u00e9langes ne sont pas r\u00e9ussis, \u00e7a fait parti du plaisir d\u2019exp\u00e9rimenter et cr\u00e9er ses propres bougies uniques.<\/p>\r\n\r\n\r\n\r\n<figure class=\"wp-block-gallery columns-2 is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\r\n<ul class=\"blocks-gallery-grid\">\r\n<li class=\"blocks-gallery-item\">\r\n<figure><img decoding=\"async\" class=\"wp-image-723\" src=\"https:\/\/cosyowl.com\/wp-content\/uploads\/2021\/08\/Screen-Shot-2020-07-09-at-11.08.18-1024x573.png\" alt=\"\" \/><\/figure>\r\n<\/li>\r\n<li class=\"blocks-gallery-item\">\r\n<figure><img decoding=\"async\" class=\"wp-image-725\" src=\"https:\/\/cosyowl.com\/wp-content\/uploads\/2021\/08\/Screen-Shot-2020-07-09-at-11.09.10-1024x574.png\" alt=\"\" \/><\/figure>\r\n<\/li>\r\n<\/ul>\r\n<\/figure>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">5<sup>\u00e8me<\/sup> Phase \u2013 Versez la cire<\/h2>\r\n\r\n\r\n\r\n<p>Une fois que vous avez fait tout ceci, prenez de l\u2019essuie-tout (pour \u00e9viter que la cire ne s\u2019\u00e9coule sur les c\u00f4t\u00e9s des pots, et commencez \u00e0 verser la cire dans les pots. Ne versez pas jusqu\u2019en haut car vous aurez besoin d\u2019un peu d\u2019espace.<\/p>\r\n\r\n\r\n\r\n<div class=\"wp-block-image\">\r\n<figure class=\"size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-724\" src=\"https:\/\/cosyowl.com\/wp-content\/uploads\/2021\/08\/Screen-Shot-2020-07-09-at-11.10.04-1024x574.png\" alt=\"\" width=\"384\" height=\"216\" \/><\/figure>\r\n<\/div>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">6<sup>\u00e8me<\/sup> Phase \u2013 V\u00e9rifiez vos bougies<\/h2>\r\n\r\n\r\n\r\n<p>Au bout d\u2019une demi-heure, v\u00e9rifier que vous bougies durcissent et r\u00e9chauffez la cire restante pour remplir d\u2019\u00e9ventuelles trous qui seraient apparus \u00e0 la surface de la bougie. Une fois cette op\u00e9ration r\u00e9alis\u00e9e, il est conseill\u00e9 de laisser la bougie refroidir pendant 24 heures.<\/p>\r\n\r\n\r\n\r\n<p>Les bougies r\u00e9alis\u00e9es avec de la cire de soja prennent en g\u00e9n\u00e9ral moins de temps \u2013 environ 5 heures pour refroidir et se solidifier. Les bougies \u00e0 la cire v\u00e9g\u00e9tale prennent un peu plus longtemps \u2013 environ 7 heures, tandis que les bougies \u00e0 la paraffine prennent le plus de temps. Vous pouvez toujours d\u00e9corer vos bougies avant de les laisser durcir 24 heures.<\/p>\r\n\r\n\r\n\r\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-735\" src=\"https:\/\/cosyowl.com\/wp-content\/uploads\/2021\/08\/Screen-Shot-2020-07-09-at-11.10.48-1-1024x574.png\" alt=\"\" width=\"384\" height=\"216\" \/><\/figure>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">7<sup>\u00e8me<\/sup> Phase \u2013 Raccourcissez la m\u00e8che<\/h2>\r\n\r\n\r\n\r\n<p>Retirez votre outil de centrage de m\u00e8che et prenez des ciseaux ou une pince \u00e0 m\u00e8che et raccourcissez la m\u00e8che jusqu\u2019\u00e0 environ 5mm de la surface de la bougie. Si vous utilisez une m\u00e8che plus longue, vous allez cr\u00e9er une flamme plus grande de fa\u00e7on initiale, mais dans la plupart des cas, celle-ci br\u00fblera tout simplement.\u00a0<\/p>\r\n\r\n\r\n\r\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-727\" src=\"https:\/\/cosyowl.com\/wp-content\/uploads\/2021\/08\/Screen-Shot-2020-07-09-at-11.12.40-1024x574.png\" alt=\"\" width=\"384\" height=\"216\" \/><\/figure>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Et voil\u00e0, vos bougies sont pr\u00eates<\/h2>\r\n\r\n\r\n\r\n<p>Baissez ou \u00e9teignez les lumi\u00e8res, relaxez-vous, mettez de la musique, et profitez de l\u2019esth\u00e9tique tranquille et de l&rsquo;ar\u00f4me d\u00e9gag\u00e9 par vos cr\u00e9ations. Ne soyez pas trop modestes et faites-en sorte que ceux qui vous entourent appr\u00e9cient votre talent.<\/p>\r\n\r\n\r\n\r\n\r\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-736\" src=\"https:\/\/cosyowl.com\/wp-content\/uploads\/2021\/08\/Screen-Shot-2020-07-08-at-15.34.27-1-1024x574.png\" alt=\"\" width=\"384\" height=\"216\" \/><\/figure>\r\n\r\n\r\n\r\n<p>D\u00e9gagement de responsabilit\u00e9 \u2013 Il est conseill\u00e9 d\u2019utiliser les fleurs uniquement pour des bougies d\u00e9coratives car celles-ci peuvent pr\u00e9senter un danger.<\/p>\r\n\r\n\r\n\r\n<p>\u00a0Si vous avez des questions ou souhaitez discuter de votre projet, n\u2019h\u00e9sitez pas \u00e0 <a href=\"https:\/\/www.cosyowl.com\/index.php?main_page=contact_us\">contacter Cosy Owl<\/a>.<\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>Nous sommes heureux de vous faire d\u00e9couvrir notre premier guide support pour ceux qui d\u00e9butent dans la fabrication de bougies maison. Faire sa premi\u00e8re bougie est une entreprise amusante et agr\u00e9able, \u00e0 laquelle beaucoup prennent go\u00fbt, gr\u00e2ce \u00e0 l\u2019abondance de fabuleuses huiles parfum\u00e9s naturelles et de colorants disponibles sur notre site. Pr\u00e9paration Tout d\u2019abord, vous [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":20751,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[308],"tags":[],"class_list":["post-20287","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fabrication-de-bougies"],"acf":[],"_links":{"self":[{"href":"https:\/\/cosyowl.com\/fr\/wp-json\/wp\/v2\/posts\/20287","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cosyowl.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cosyowl.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cosyowl.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/cosyowl.com\/fr\/wp-json\/wp\/v2\/comments?post=20287"}],"version-history":[{"count":0,"href":"https:\/\/cosyowl.com\/fr\/wp-json\/wp\/v2\/posts\/20287\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cosyowl.com\/fr\/wp-json\/wp\/v2\/media\/20751"}],"wp:attachment":[{"href":"https:\/\/cosyowl.com\/fr\/wp-json\/wp\/v2\/media?parent=20287"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cosyowl.com\/fr\/wp-json\/wp\/v2\/categories?post=20287"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cosyowl.com\/fr\/wp-json\/wp\/v2\/tags?post=20287"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}