{"id":1109,"date":"2018-01-24T15:40:00","date_gmt":"2018-01-24T15:40:00","guid":{"rendered":"https:\/\/www.cosyowl.com\/guides\/?p=1109"},"modified":"2025-10-10T15:37:25","modified_gmt":"2025-10-10T13:37:25","slug":"depannage","status":"publish","type":"post","link":"https:\/\/cosyowl.com\/fr\/guides\/depannage","title":{"rendered":"D\u00e9pannage"},"content":{"rendered":"\r\n<p>Vous trouverez ci-dessous une liste des probl\u00e8mes les plus courants li\u00e9s \u00e0 la fabrication de bougies. M\u00eame les meilleurs d&rsquo;entre nous peuvent rencontrer ces probl\u00e8mes \u00e0 l&rsquo;occasion. Soyez toujours patient avec votre fabrication de bougies et appr\u00e9ciez le passe-temps, devenant plus adaptable \u00e0 mesure que vous devenez plus exp\u00e9riment\u00e9. Parfois, vous ne pouvez pas faire grand-chose pour r\u00e9soudre un probl\u00e8me une fois que la bougie s&rsquo;est solidifi\u00e9e; nous recommandons toujours de dire \u00e0 votre famille et \u00e0 vos amis que ce qui s&rsquo;est pass\u00e9 \u00e9tait d\u00e9lib\u00e9r\u00e9 et tr\u00e8s intelligemment fait.<\/p>\r\n\r\n\r\n\r\n<p>Si vous trouvez un <strong>effet de bulles<\/strong> dans votre bougie finie, cela peut \u00eatre d\u00fb au fait que la cire n&rsquo;est pas dans la plage de temp\u00e9rature recommand\u00e9e ou que la cire a \u00e9t\u00e9 perturb\u00e9e pendant le processus de refroidissement.<\/p>\r\n\r\n\r\n\r\n<p><strong>J&rsquo;ai un effet \u00abtunnel\u00bb avec ma bougie<\/strong> o\u00f9 l\u2019ext\u00e9rieur de la bougie ne fond pas aussi vite que l\u2019int\u00e9rieur. Finalement, la m\u00e8che br\u00fble, ce qui laisse la moiti\u00e9 de la cire. Ceci est simplement caus\u00e9 par une m\u00e8che trop petite. Essayez la taille suivante lors de la fabrication de cette taille de bougie \u00e0 l&rsquo;avenir. V\u00e9rifiez la taille de la m\u00e8che n\u00e9cessaire (en fonction du diam\u00e8tre de la bougie) en utilisant les informations disponibles dans notre section m\u00e8che de bougie &#8211; lors de la s\u00e9lection d&rsquo;une m\u00e8che particuli\u00e8re, cliquez sur l&rsquo;onglet \u00abDiam\u00e8tre de la bougie\u00bb.<\/p>\r\n\r\n\r\n\r\n<p id=\"tw-target-text\"><strong>Des trous d&rsquo;\u00e9vier<\/strong> (\u00e9galement appel\u00e9s \u00abpuits\u00bb) peuvent appara\u00eetre au sommet de la bougie pendant le processus de refroidissement. Cela peut se produire pour de nombreuses raisons et est tr\u00e8s courant. Comme pour l&rsquo;effet de bulles, le risque que cela se produise peut \u00eatre r\u00e9duit en s&rsquo;assurant que la cire est \u00e0 la bonne temp\u00e9rature lors du versement. Pour r\u00e9soudre ce probl\u00e8me, ajoutez simplement plus de cire chaude (\u00e0 la temp\u00e9rature appropri\u00e9e) pour remplir les trous. Vous devez vous assurer que la bougie est compl\u00e8tement solidifi\u00e9e avant d&rsquo;ajouter plus de cire. Laisser cette cire ajout\u00e9e se solidifier avant de retirer la bougie du moule \/ r\u00e9cipient. Un autre rem\u00e8de \u00e0 ce probl\u00e8me, qui peut parfois fonctionner, consiste \u00e0 pr\u00e9chauffer le r\u00e9cipient avant de verser la cire.<\/p>\r\n\r\n\r\n\r\n<p id=\"tw-target-text\"><strong>La m\u00e8che g\u00e9n\u00e8re de la fum\u00e9e<\/strong>. Cela peut survenir pour plusieurs raisons. Une cause commune est si la m\u00e8che est trop longue au sommet de la bougie; soufflez la bougie et r\u00e9duisez la longueur de la m\u00e8che \u00e0 environ 1 cm. Une autre raison est que la m\u00e8che utilis\u00e9e est significativement trop grande par rapport au diam\u00e8tre de la bougie. Cet effet de fum\u00e9e peut \u00e9galement se produire si une trop grande quantit\u00e9 d&rsquo;additif a \u00e9t\u00e9 utilis\u00e9e dans votre m\u00e9lange de cire de bougie &#8211; r\u00e9duisez simplement la quantit\u00e9 utilis\u00e9e. \u00c9vitez \u00e9galement de placer la bougie l\u00e0 o\u00f9 il pourrait y avoir un courant d&rsquo;air.<\/p>\r\n\r\n\r\n\r\n<p id=\"tw-target-text\"><strong>La bougie ne cesse de s&rsquo;\u00e9teindre<\/strong>. Essayez d&rsquo;amorcer la m\u00e8che de bougie en l&rsquo;enduisant de cire (en laissant \u00e0 la m\u00e8che le temps d&rsquo;absorber la couche de cire) et en la laissant se solidifier avant d&rsquo;ajouter votre cire fondue. Cela peut \u00e9galement se produire si vous utilisez une m\u00e8che de bougie trop fine pour le diam\u00e8tre de la bougie. Une autre raison \u00e0 cela concerne le type et la qualit\u00e9 de tout colorant de bougie ajout\u00e9 au m\u00e9lange. Chez Cozy Owl, nous ne vendons pas de colorants contenant des pigments; c&rsquo;est ce qui peut contaminer la m\u00e8che de la bougie lorsqu&rsquo;elle br\u00fble.<\/p>\r\n\r\n\r\n\r\n<p id=\"tw-target-text\"><strong>La m\u00e8che semble \u00abprolif\u00e9rer\u00bb<\/strong>. C&rsquo;est l\u00e0 que la m\u00e8che br\u00fbl\u00e9e commence \u00e0 se tordre et \u00e0 s&rsquo;enrouler, souvent avec des parties de m\u00e8che non br\u00fbl\u00e9es toujours attach\u00e9es. Cela est d\u00fb \u00e0 une accumulation ind\u00e9sirable de carbone et est g\u00e9n\u00e9ralement le r\u00e9sultat d&rsquo;une m\u00e8che de bougie trop grande pour le diam\u00e8tre de la bougie.<\/p>\r\n\r\n\r\n\r\n<p id=\"tw-target-text\"><strong>La m\u00e8che a boug\u00e9<\/strong> pendant le processus de refroidissement. Cela peut se produire si la m\u00e8che n&rsquo;a pas \u00e9t\u00e9 tendue d\u00e8s le d\u00e9but du processus de refroidissement.<\/p>\r\n\r\n\r\n\r\n<p><strong>La bougie \u00e9tait fissur\u00e9e quand je l&rsquo;ai retir\u00e9e du moule<\/strong>. Cela se produit lorsque la bougie a \u00e9t\u00e9 refroidie trop rapidement. Les bougies doivent g\u00e9n\u00e9ralement pouvoir refroidir \u00e0 temp\u00e9rature ambiante mod\u00e9r\u00e9e. Ne placez pas la bougie dans le r\u00e9frig\u00e9rateur ou le cong\u00e9lateur pour tenter d&rsquo;acc\u00e9l\u00e9rer le processus de solidification de la cire.<\/p>\r\n\r\n\r\n\r\n<p>J&rsquo;ai de <strong>l&rsquo;huile parfum\u00e9e qui suinte de la bougie<\/strong>. La cause la plus fr\u00e9quente de ceci est l&rsquo;utilisation d&rsquo;une trop grande quantit\u00e9 d&rsquo;huile parfum\u00e9e m\u00e9lang\u00e9e \u00e0 la cire de bougie fondue. Si cela devient un probl\u00e8me r\u00e9gulier, en raison de la quantit\u00e9 d&rsquo;huile parfum\u00e9e que vous souhaitez utiliser, le probl\u00e8me peut \u00eatre r\u00e9solu en incorporant une solution de durcissement dans le m\u00e9lange de cire fondue. Bien que nous ne puissions pas recommander une marque particuli\u00e8re, un exemple d&rsquo;un tel agent est Vybar.<\/p>\r\n\r\n\r\n\r\n<p><strong>La cire a pris feu dans la po\u00eale!<\/strong> De toute \u00e9vidence, la temp\u00e9rature de la cire \u00e9tait nettement sup\u00e9rieure \u00e0 celle requise. Assurez-vous d&rsquo;utiliser un thermom\u00e8tre \u00e0 cire et cela ne devrait pas arriver. Beaucoup de gens pensent que la cire seule ne peut pas prendre feu. Ils ont tort. Dans un tel cas, utilisez une serviette en T imbib\u00e9e d&rsquo;eau ou une couverture anti-feu pour couvrir la casserole; apr\u00e8s quelques instants, retirez d\u00e9licatement la casserole du feu. Si vous utilisez un extincteur (si les choses deviennent vraiment graves), n&rsquo;appliquez pas d&rsquo;eau, utilisez de pr\u00e9f\u00e9rence de la poudre.<\/p>\r\n\r\n\r\n\r\n<p><strong>J&rsquo;ai de la cire sur toute la surface de mon comptoir<\/strong>. Utilisez une spatule ou une louche en plastique pour gratter doucement la cire de la surface. Une fois que la majorit\u00e9 a \u00e9t\u00e9 enlev\u00e9e, utilisez un chiffon jetable raisonnablement chaud (mat\u00e9riaux ou de pr\u00e9f\u00e9rence du papier) pour enlever ce qui reste. \u00c9liminez-le en toute s\u00e9curit\u00e9.<\/p>\r\n\r\n\r\n\r\n<p><strong>J&rsquo;ai de la cire sur mes v\u00eatements<\/strong>. Pour enlever la cire des v\u00eatements, ne grattez pas d&rsquo;abord la cire ou vous endommagerez le tissu. Placez les v\u00eatements sur une planche \u00e0 repasser avec quelques couches de serviette en papier sous le mat\u00e9riau effectu\u00e9. Maintenant, placez quelques serviettes en papier sur le mat\u00e9riau avec un d\u00e9p\u00f4t de cire et utilisez un fer \u00e0 repasser pour enlever la cire. La cire sera enlev\u00e9e des v\u00eatements et absorb\u00e9e par la serviette en papier. R\u00e9glez le fer \u00e0 une temp\u00e9rature basse \u00e0 moyenne. Si vous avez renvers\u00e9 de <strong>la cire sur un tapis<\/strong>, vous pouvez faire plus ou moins la m\u00eame chose pour l&rsquo;enlever &#8211; soyez juste tr\u00e8s prudent, r\u00e9glez d&rsquo;abord le fer \u00e0 basse temp\u00e9rature et augmentez-le seulement, si vous \u00eates s\u00fbr que cela n&rsquo;endommagera pas le tissu du tapis. Ne laissez pas le fer reposer sur la surface du mat\u00e9riau \/ tapis &#8211; gardez le fer en mouvement.<\/p>\r\n\r\n\r\n\r\n<p><strong>La couleur commence \u00e0 s&rsquo;estomper<\/strong>. Presque toutes les bougies color\u00e9es peuvent commencer \u00e0 s&rsquo;estomper si elles sont plac\u00e9es \u00e0 la lumi\u00e8re directe du soleil pendant des p\u00e9riodes prolong\u00e9es. Bien qu&rsquo;il soit facile de dire d&rsquo;ajouter plus de colorant lors de la fabrication de la bougie, vous pouvez vous retrouver avec une bougie plus ch\u00e8re \u00e0 fabriquer et peut-\u00eatre d&rsquo;une couleur plus forte que vous ne le souhaitez. Une fa\u00e7on d&rsquo;\u00e9viter la d\u00e9coloration consiste \u00e0 ranger la bougie dans une armoire ou dans une zone sombre d&rsquo;une pi\u00e8ce. Les professionnels utiliseront un inhibiteur UV pour prolonger la p\u00e9riode pendant laquelle la bougie conservera sa couleur. Chez Cozy Owl, nous ne fournissons que des colorants de haute qualit\u00e9 &#8211; d&rsquo;autres colorants pour bougies de qualit\u00e9 inf\u00e9rieure ne permettent pas \u00e0 la bougie de conserver sa couleur aussi longtemps.<\/p>\r\n\r\n\r\n\r\n<p><strong>Je peux voir des taches de teinture sur la surface<\/strong> et \/ ou sur les c\u00f4t\u00e9s de ma bougie. Cela peut se produire lorsque le colorant n&rsquo;a pas \u00e9t\u00e9 compl\u00e8tement dissous dans la cire fondue. Assurez-vous de bien m\u00e9langer avant de verser dans votre r\u00e9cipient.<\/p>\r\n\r\n\r\n\r\n<p><strong>Le dessus de la bougie est fissur\u00e9<\/strong>. Cela peut \u00eatre r\u00e9solu en utilisant un s\u00e8che-cheveux pour faire fondre l\u00e9g\u00e8rement la surface de la bougie jusqu&rsquo;\u00e0 ce que les fissures disparaissent.<\/p>\r\n\r\n\r\n\r\n<p>&nbsp;<\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>Vous trouverez ci-dessous une liste des probl\u00e8mes les plus courants li\u00e9s \u00e0 la fabrication de bougies. M\u00eame les meilleurs d&rsquo;entre nous peuvent rencontrer ces probl\u00e8mes \u00e0 l&rsquo;occasion. Soyez toujours patient avec votre fabrication de bougies et appr\u00e9ciez le passe-temps, devenant plus adaptable \u00e0 mesure que vous devenez plus exp\u00e9riment\u00e9. Parfois, vous ne pouvez pas faire [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":20670,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[323,203],"tags":[],"class_list":["post-1109","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-depannage","category-faq-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/cosyowl.com\/fr\/wp-json\/wp\/v2\/posts\/1109","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cosyowl.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cosyowl.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cosyowl.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/cosyowl.com\/fr\/wp-json\/wp\/v2\/comments?post=1109"}],"version-history":[{"count":0,"href":"https:\/\/cosyowl.com\/fr\/wp-json\/wp\/v2\/posts\/1109\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cosyowl.com\/fr\/wp-json\/wp\/v2\/media\/20670"}],"wp:attachment":[{"href":"https:\/\/cosyowl.com\/fr\/wp-json\/wp\/v2\/media?parent=1109"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cosyowl.com\/fr\/wp-json\/wp\/v2\/categories?post=1109"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cosyowl.com\/fr\/wp-json\/wp\/v2\/tags?post=1109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}